{"id":149246,"date":"2022-05-31T09:00:48","date_gmt":"2022-05-31T13:00:48","guid":{"rendered":"https:\/\/colobar.ca\/the-ultimate-guide-to-staining-a-wooden-deck\/"},"modified":"2026-05-05T15:15:08","modified_gmt":"2026-05-05T19:15:08","slug":"the-ultimate-guide-to-staining-a-wooden-deck","status":"publish","type":"post","link":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/","title":{"rendered":"The Ultimate Guide to Staining a Wooden Deck"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;2%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-2-percent&#8221; column_padding_position=&#8221;left-right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;3%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-signal extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> Difficulty: Medium <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-tag extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> Cost per sq ft = $0.97 to $1.57 <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; column_link=&#8221;https:\/\/colobar.ca\/produits\/?filter_articles=effet-beton&#8221; gradient_type=&#8221;default&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-check-circle extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> Products: In stock<br \/>\nDelivery: Ready to ship anywhere in Canada <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-thumbs-up extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> <strong>Sylvain (Verified Customer)<\/strong><\/p>\n<p>&#8220;We have been using Sansin for over 10 years and we truly love this product. It applies easily and protects the wood for years.&#8221; <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;60px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Staining a patio is a project anyone can handle. However, achieving a beautiful result that lasts over time requires a bit more than simply applying a product. <\/p>\n<p>Several details make all the difference: preparation, product selection, weather conditions, and application technique. Over the years, we&#8217;ve seen many successful projects&#8230; and some less so. Here, we share the essential points to master to put all the odds in your favor.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;01&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Cleaning the Deck&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;60px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]A successful staining project always begins with a thorough cleaning.<\/p>\n<p>The goal is to eliminate contaminants, residues, and microorganisms present on the wood surface. Even if you plan to sand, it is important to start by cleaning. <\/p>\n<p>Why? Because by sanding a dirty surface, you risk spreading contaminants across the entire surface&#8230; and even embedding them into the wood.<\/p>\n<p>In the case of a patio that has grayed, it is even more critical. Sanding can remove some visible stains, but certain fungi remain embedded in the wood fibers. As a result, graying quickly reappears, often as dark spots that detract from the uniformity of the finish.  <\/p>\n<h3>Which cleaner should you use for your patio?<\/h3>\n<p>The choice of product depends directly on the condition of your wood.<br \/>\n<strong>  If your patio has completely grayed, the ideal is to use a <a href=\"https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-wood-wash-wood-cleaner-and-brightener-decks-and-fences\/\">wood brightener<\/a>.  <\/strong><\/p>\n<p>This type of product helps restore your wood&#8217;s original color and give it a more uniform appearance before stain application. <a href=\"https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-wood-wash-wood-cleaner-and-brightener-decks-and-fences\/\">Wood Wash<\/a> is an excellent choice for a wood brightener.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1776176676536{background-color: #88988D !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;47436&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-wood-wash-wood-cleaner-and-brightener-decks-and-fences\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_star_rating star_rating=&#8221;5&#8243; icon_color=&#8221;accent-color&#8221;][\/nectar_star_rating][nectar_single_testimonial testimonial_style=&#8221;basic&#8221; quote=&#8221;Excellent product for brightening patio wood. Exceeded my expectations. The wood was completely black and regained its natural color.  &#8221; name=&#8221;Andr\u00e9 (client confirm\u00e9)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;\u00e9tanch\u00e9it\u00e9&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>To ensure the patio is clean and to eliminate slight graying<\/strong>.<br \/>\nIf your patio is in relatively good condition, a patio maintenance cleaner is sufficient. It helps remove grease, dust, salt, and contaminants accumulated during winter. <\/p>\n<p>Furthermore, <strong>cleaning in the spring<\/strong> is a simple habit that greatly helps prolong the life of your stain.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1776176676536{background-color: #88988D !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;47434&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-multi-wash-concentrated-biodegradable-cleaner\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_star_rating star_rating=&#8221;5&#8243; icon_color=&#8221;accent-color&#8221;][\/nectar_star_rating][nectar_single_testimonial testimonial_style=&#8221;basic&#8221; quote=&#8221;I had tried several products to clean my Sansin Dec-treated deck, which had become dull with dirt and mud, without success. I thought it was ruined! The multiwash diluted 1 part to 5 parts water restored its original appearance! \ud83d\ude00<br \/>\nThis is THE product I needed!&#8221; name=&#8221;Cliente Satisfaite (cliente confirm\u00e9e)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;\u00e9tanch\u00e9it\u00e9&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Can I use a pressure washer to clean my patio?<\/h3>\n<p>Yes, you can absolutely use your pressure washer to clean your patio! It&#8217;s even faster and requires less effort! However, you must still take several precautions to avoid damaging your wood.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;105174&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/nettoyer-patio-header-scaled.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;\u00e9tanch\u00e9it\u00e9&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]You must always <strong>maintain a distance of 12 to 18 inches<\/strong> between the nozzle and the wood. If you do not respect this distance, you risk damaging your wood.<br \/>\nThe same applies to pressure: we recommend <strong>not exceeding approximately 500 psi<\/strong> to avoid deteriorating your patio boards.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;02&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Patio Sanding: The Key to a Stain That Doesn&#039;t Peel&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;pr\u00e9paration&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]When it comes to staining, <strong>sanding is probably the most important step.<\/strong><br \/>\nIt allows you to <strong>open the pores of the wood and ensure good penetration<\/strong> of the stain. Without this porosity, the stain remains on the surface, which increases the risk of peeling.<br \/>\nWe cannot repeat it often enough: good sanding is often what makes the difference between a stain that peels and a stain that wears gradually over the years. <strong>Whether your patio boards are old or new, it is important that you sand them<\/strong>. We explain why.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;116695&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/Colobar-sablage-teindre-un-patio-en-bois.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;pr\u00e9paration&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Why sand aged wood?<\/h3>\n<p>Over time, not all boards age in the same way. Some areas become more porous, while others remain more closed. <\/p>\n<p>This variation creates a problem during application: the stain penetrates more in some areas and less in others. As a result, you end up with an uneven finish, darker in some places and lighter in others. <\/p>\n<p>Sanding helps to even out the surface and remove dead wood cells. These cells, in addition to being unsightly, hinder stain adhesion. <\/p>\n<p>If your patio has already been stained and the finish is starting to peel, sanding becomes even more important. It helps prevent adhesion problems and reactions between different products.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3091&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/colobar-patio-cedre-5-e1723131548538.png&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;pr\u00e9paration&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Why you should sand your patio even when it&#8217;s new<\/h3>\n<p>Even <strong>new wood must be sanded<\/strong>.<\/p>\n<p>During manufacturing, <strong>boards are planed to obtain a uniform surface.<\/strong> This process creates what is called <strong>a mill glaze, which closes the pores of the wood.<\/strong><\/p>\n<p>This glaze prevents the stain from penetrating correctly. <strong>By lightly sanding, you remove this layer and restore the wood&#8217;s absorption capacity.<\/strong><\/p>\n<p>This is <strong>a simple but essential step to ensure the durability<\/strong> of the finish.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;03&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Choosing the right sander for your patio&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;]\u00a0[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;m\u00e9langer&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Large floor sanders may seem practical, but they are not suitable for patios.<\/p>\n<p>They have difficulty reaching the joints between boards, and their movement is not ideal for following the wood grain.<\/p>\n<p><strong>An orbital or rotary sander with a 5 to 6-inch disc remains the best choice<\/strong>. It allows for more precise and uniform work, even if it takes a little more time.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;116698&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/sableuse-teindre-un-patio-en-bois.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;m\u00e9langer&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]By sanding board by board, you ensure that your sanding is impeccable. This way, your stain will remain uniform longer![\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;04&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;How to achieve successful sanding&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; el_id=&#8221;finition&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>\n<h3>Always sand with the grain of the wood<\/h3>\n<\/li>\n<\/ul>\n<p>This may seem like a trivial detail, but <strong>it makes a huge difference<\/strong> to the final result. By sanding with the grain, you <strong>avoid creating cross-grain marks<\/strong> that may show through once the stain is applied. In addition to having a more beautiful finish, you also <strong>facilitate the penetration<\/strong> of the stain into the wood.  <\/p>\n<ul>\n<li>\n<h3>Choose the right sandpaper<\/h3>\n<\/li>\n<\/ul>\n<p>The choice of sandpaper <strong>directly influences the quality of your sanding&#8230;<\/strong> and the level of effort you need to put into it. Good quality paper <strong>will work more efficiently<\/strong>, <strong>last longer<\/strong>, and <strong>prevent you from having to force the machine<\/strong>. <\/p>\n<p>At Colobar, we often recommend <strong>80-grit<\/strong> to sufficiently open the pores of the wood and promote good stain penetration. That said, <strong>the correct grit can vary depending on the wood species and the product used<\/strong>. When in doubt, always take the time to check the manufacturer&#8217;s recommendations.  <\/p>\n<ul>\n<li>\n<h3>Change sandpaper often<\/h3>\n<\/li>\n<\/ul>\n<p>It&#8217;s tempting to extend the life of your <a href=\"https:\/\/colobar.ca\/en\/produits\/application-tools-and-sandpaper\/5-8-hole-hook-and-loop-sandpaper-disc-for-orbital-sander\/\">sandpaper<\/a>&#8230; but ultimately, it often makes you lose time (and energy). <strong>Worn paper becomes much less effective<\/strong> and forces you to press harder on the sander.<\/p>\n<p>As a result, you risk <strong>creating undesirable marks in the wood<\/strong> and getting a less uniform sanding. Ideally, change your paper approximately every 25 sq ft, or even more often if you are working on very resinous wood.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1776176676536{background-color: #88988D !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;20099&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/application-tools-and-sandpaper\/5-8-hole-hook-and-loop-sandpaper-disc-for-orbital-sander\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_star_rating star_rating=&#8221;3-5&#8243; sizing=&#8221;0&#8243; icon_color=&#8221;accent-color&#8221;][\/nectar_star_rating][nectar_single_testimonial testimonial_style=&#8221;basic&#8221; quote=&#8221;Very good product, only problem: during my first order I received papers without holes and I expected to receive the same thing this time, which suited me because the hole-less ones were very good, but I received them with holes&#8230; they are still very effective.&#8221; name=&#8221;Pierre Dery (client confirm\u00e9)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>\n<h3>Stain within days of sanding<\/h3>\n<\/li>\n<\/ul>\n<p>Once your patio is sanded, the wood is at its maximum porosity.<strong> This is exactly the state you want it to be in when you apply your stain<\/strong>.<\/p>\n<p>Over time, the wood pores will naturally close, especially depending on weather conditions. <strong>If you wait too long, you may have to sand again<\/strong> to regain a good adhesion surface. In short, as soon as the weather permits, apply the stain without too much delay. <\/p>\n<ul>\n<li>\n<h3>Dry dust the patio<\/h3>\n<\/li>\n<\/ul>\n<p>After sanding, it is essential <strong>to remove all dust before applying your stain<\/strong>. But be careful how you do it. <\/p>\n<p>We recommend <strong>dry dusting, with a broom or a vacuum cleaner<\/strong>. If you rinse with water, you will re-wet the wood&#8230; and have to wait at least 24 hours before you can continue. <\/p>\n<p>Worse still: some of the dust-laden water can penetrate the wood and clog the pores you just opened. This means the stain penetrates less effectively, and your finish is compromised from the start.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;116701&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/depoussierer-a-sec-teindre-un-patio-en-bois.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;04&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Pro tips for staining your patio&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Once the preparation is complete, application becomes much simpler. This is often the most enjoyable step of the project. <\/p>\n<p>We still have some tips to share for a smooth application and a flawless result.<\/p>\n<h3>Choose the right brush<\/h3>\n<p>Use a brush specifically designed for staining. These brushes are normally designed primarily with natural bristles.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1776176676536{background-color: #88988D !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;93238&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/produits\/outils-de-pose\/pinceaux\/pinceau-a-teinture-manche-devissable-6po\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>2 to 3 business days delivery<\/p>\n<li style=\"list-style-type: none;\">\n<ul>Same-day in-store pickup<\/ul>\n<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div>Natural bristles <strong>retain stain better<\/strong> and allow for good saturation of the wood. As stain is more liquid than paint, <strong>this absorption capacity is essential for achieving a uniform application<\/strong>. <\/div>\n<div><\/div>\n<ul>\n<li>\n<h3>Opt for a brush with a detachable handle<\/h3>\n<\/li>\n<\/ul>\n<div>When staining a medium or large patio, <a href=\"https:\/\/colobar.ca\/produits\/outils-de-pose\/pinceaux\/pinceau-a-teinture-manche-devissable-6po\/\">a brush with a detachable handle<\/a> is a great asset. By attaching your brush to an extendable pole (or simply a broom handle), <strong>you save your knees<\/strong>. But most importantly: you <strong>get better reach<\/strong>. This helps <strong>avoid overlap marks.<\/strong>   <\/div>\n<div><\/div>\n<div><\/div>\n<div>Since stain is very liquid (especially semi-transparent), it is <strong>quickly absorbed by the wood<\/strong>. Even more so if you apply the stain in hot weather. What does this imply? That <strong>there isn&#8217;t much time to work the stain<\/strong> once it&#8217;s applied to the wood. You will therefore greatly appreciate the extra reach and speed of application that <a href=\"https:\/\/colobar.ca\/en\/produits\/application-tools\/brushes\/4-inch-stain-brush-with-removable-handle\/\">a brush with a detachable handle<\/a> provides.    <\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1776176676536{background-color: #88988D !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;18940&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/produits\/outils-de-pose\/pinceaux\/pinceau-a-teinture-manche-devissable-6po\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_star_rating star_rating=&#8221;5&#8243; icon_color=&#8221;accent-color&#8221;][\/nectar_star_rating][nectar_single_testimonial testimonial_style=&#8221;small_modern&#8221; color=&#8221;Default&#8221; quote=&#8221;&#039;&#039;Excellent achat, pas mal plus facile de travailler debout qu\u2019\u00e0 quatre pattes.<br \/>\nLe pinceau est d\u2019excellente qualit\u00e9&#039;&#039;<br \/>\nDenis Marcil (client confirm\u00e9)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<ul>\n<li>\n<h3>Apply the stain one or two boards at a time.<\/h3>\n<\/li>\n<\/ul>\n<div>To <strong>avoid overlap marks<\/strong> and visible touch-ups, the best approach is to <strong>work one board at a time<\/strong>. You can do 2 to 3 at the same time to gain a little speed, but the idea is to <strong>maintain control over your application<\/strong>. <\/div>\n<div><\/div>\n<div>By working this way, you <strong>ensure that the stain remains wet along the entire length of the board<\/strong>. This allows you to <strong>continue your application without creating demarcation lines<\/strong> between sections. <\/div>\n<div><\/div>\n<div>If you need to stop, <strong>always take the time to finish the current board.<\/strong> In just a few minutes, the stain already begins to penetrate the wood. <strong>If you resume in the middle of a board, there is a high chance it will show<\/strong>.<\/div>\n<div><\/div>\n<ul>\n<li>\n<h3>Apply with the grain<\/h3>\n<\/li>\n<\/ul>\n<div><\/div>\n<div>As with sanding, the direction of application is essential. <strong>By following the wood grain, you reduce visible brush strokes<\/strong> and achieve a much more uniform finish.<\/div>\n<div><\/div>\n<div>But it&#8217;s not just about aesthetics. By applying the stain with the grain, <strong>you also help the product penetrate the wood better<\/strong>. Your finish will be more durable and resistant over time.  <\/div>\n<div><\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;116703&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/Teindre-un-patio-en-bois-application-pinceau-sansin-dec.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div>\n<div><\/div>\n<ul>\n<li>\n<h3>Is it possible to apply stain with a sprayer?<\/h3>\n<\/li>\n<\/ul>\n<div>Yes, a sprayer <strong>can be a good tool to speed up application<\/strong>, especially on large surfaces. It allows for quick and uniform application of stain to the patio. <\/div>\n<div><\/div>\n<div>However, after spraying, <strong>it is essential that you go over it with a staining brush<\/strong>. This step will allow you to <strong>ensure the stain penetrates the wood well<\/strong> and to even it out. <\/div>\n<div><\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;116705&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/teindre-un-patio-en-bois-pulverisateur.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div>\n<div><\/div>\n<ul>\n<li>\n<h3>Refreshing your stain: better to prevent than to sand<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>When it comes to maintaining your patio, the reflex to adopt is simple: <strong>don&#8217;t wait until it&#8217;s too late<\/strong>.<\/p>\n<p>If you let <strong>your stain wear completely down to bare wood,<\/strong> you will have no choice but to start from scratch&#8230; meaning <strong>complete sanding<\/strong>. And that is by far the longest and most demanding step of the project. <\/p>\n<p>Conversely, if you <strong>remain attentive and apply a maintenance coat<\/strong> as soon as the finish begins to dull or weaken, <strong>you can avoid all that work<\/strong>. You prolong the life of your stain without having to start all over again. <\/p>\n<p>Another important point: applying a maintenance coat to an already too worn patio rarely yields a good result. Areas where the wood is bare will not react the same way as those where there is still stain. This results in an uneven finish, with visible color variations.  <\/p>\n<p>By maintaining a preventive approach, you ensure a more uniform, more durable patio&#8230; and you save yourself a lot of effort in the long run.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;10px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3090&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/colobar-patio-cedre-4.png&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Products found in this article.&#8221; font_container=&#8221;tag:h3|font_size:20|text_align:center|color:%23333333&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;44577&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;5%&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/exterior-stain\/sansin-dec-wood-deck-stain\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text css=&#8221;.vc_custom_1777537891214{padding-bottom: 5% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><strong>Sansin DEC &#8211; teinture pour patios en bois\u00a0<\/strong><\/p>\n[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Add to cart&#8221; url=&#8221;https:\/\/colobar.ca\/en\/produits\/exterior-stain\/sansin-dec-wood-deck-stain\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;130795&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;5%&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/outdoor-oils\/alis-by-livos-exterior-wood-protection-oil\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text css=&#8221;.vc_custom_1777538076327{padding-bottom: 5% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><strong>Huile de protection pour bois ext\u00e9rieur Alis de Livos<\/strong><\/p>\n[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Add to cart&#8221; url=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/outdoor-oils\/alis-by-livos-exterior-wood-protection-oil\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][image_with_animation image_url=&#8221;47434&#8243; image_size=&#8221;full&#8221; max_width=&#8221;75%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;5%&#8221; img_link=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-multi-wash-concentrated-biodegradable-cleaner\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][vc_column_text css=&#8221;.vc_custom_1777539138930{padding-bottom: 5% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\"><strong>Nettoyant pour terrasse Multi wash\u00a0<\/strong><\/p>\n[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Add to cart&#8221; url=&#8221;https:\/\/colobar.ca\/en\/produits\/wood-treatment\/cleaners\/sansin-multi-wash-concentrated-biodegradable-cleaner\/&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;1%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;1%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#e4e0db&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#88988d&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;3px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; column_link=&#8221;https:\/\/colobar.ca\/produits\/?filter_articles=guide-patio&#8221; content_layout=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1723059906579{margin-top: 2% !important;margin-bottom: 2% !important;padding-top: 2% !important;padding-right: 2% !important;padding-bottom: 2% !important;padding-left: 2% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: center;\">Voir plus&#8230;<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;3263&#8243; image_size=&#8221;full&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom-crop&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/sansin-dec-application\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#efefef&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1569518583590{margin-bottom: 10px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-md-offset-0 vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;11\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;This video shows you in detail how to apply Sansin DEC stain to a cedar patio.&#8221; text_direction=&#8221;default&#8221;]\n[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-md-offset-0 vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;11\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_column_text css=&#8221;.vc_custom_1776294646414{padding-right: 10% !important;}&#8221; text_direction=&#8221;default&#8221;]\n<p>We invite you to watch this video capsule to learn all the tips and tricks for a successful patio staining project.<\/p>\n[\/vc_column_text][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; text_color=&#8221;#0a0000&#8243; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Read the article&#8221; url=&#8221;https:\/\/colobar.ca\/sansin-dec-application\/&#8221; margin_top=&#8221;20&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#88988d&#8221; content_alignment=&#8221;left&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;05&#8243; font_size=&#8221;6vw&#8221; font_line_height=&#8221;1&#8243; font_size_phone=&#8221;65&#8243; font_size_tablet=&#8221;70&#8243; text_direction=&#8221;default&#8221;]\n[\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-8&#8243; column_padding_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Weather: factors you cannot overlook&#8221; font_size=&#8221;2vw&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]When you embark on a patio staining project, the weather plays a much more important role than you might think. In many cases, <strong>the problems we see \u2014 peeling, premature wear, uneven finish \u2014 are directly related to the weather conditions<\/strong> at the time of application. <\/p>\n<p>If you want to avoid these problems, it is absolutely necessary to <strong>apply your stain in good conditions<\/strong>. This will allow the product to penetrate the wood properly and perform as it should over time. <\/p>\n<p>One point not to be overlooked: <strong>not all stains react in the same way<\/strong>. Some products tolerate a little more humidity, others much less. That&#8217;s why, no matter your project, <strong>you must always refer to the manufacturer&#8217;s recommendations<\/strong>.  <\/p>\n<p>By respecting the right conditions from the start, you put all the chances on your side.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;116165&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/maison-bois-rond-header.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<div>\n<div><\/div>\n<ul>\n<li>\n<h3>The wood must be completely dry before staining<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>Before you even think about applying your stain, make sure of one thing: your wood must be dry. Not just on the surface&#8230; truly dry deep down. <\/p>\n<p>Why is this so important? Because if the wood pores are filled with water, the stain will not be able to penetrate correctly. It will remain on the surface, adhere superficially&#8230; and eventually peel much faster.  <\/p>\n<p>Imagine your boards like a sponge. If it&#8217;s already full of water, no matter how much you dip it in stain, it won&#8217;t absorb anything. It&#8217;s exactly the same principle with your patio.  <\/p>\n<p>In addition to hindering penetration, humidity can also dilute the stain during application, which will affect the performance of your finish.<\/p>\n<p>In most cases, it is recommended <strong>to wait at least 24 hours after rain before staining<\/strong>. After heavy rain, or depending on the product used, <strong>this can extend to 48 to 72 hours<\/strong>. <\/p>\n<div>\n<div><\/div>\n<ul>\n<li>\n<h3>In spring: allow time for the wood to dry<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>With the snowmelt, <strong>your patio is often saturated with water in early spring<\/strong>. Even if the surface may seem dry, moisture remains present in the wood. <\/p>\n<p>That&#8217;s why <strong>early spring is generally not the right time to stain<\/strong>. It&#8217;s better to let the warmth and sun do their work, and wait until the wood has dried thoroughly before applying anything. <\/p>\n<p>However, <strong>this period is ideal for preparing your patio: cleaning, inspection, minor repairs<\/strong>&#8230; Everything that will allow you to be ready as soon as conditions are right for staining.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;39280&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; img_link=&#8221;https:\/\/colobar.ca\/wp-content\/uploads\/accueil-entretien-nettoyage-printanier.jpg&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;3%&#8221; top_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-4&#8243; column_padding_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Generally, we <strong>recommend waiting until mid-May or early June before sanding and staining your patio<\/strong>. Obviously, <strong>this can vary from year to year<\/strong>, but the idea remains the same: allow the wood time to dry completely after winter. Rushing too early is often when problems begin.  <\/p>\n<div><\/div>\n<ul>\n<li>\n<h3>Respect the correct temperature range<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>For your stain to perform as expected, <strong>the air and surface temperatures should ideally be between 10\u00b0C and 25\u00b0C<\/strong>. And this is not just during application. <strong>As long as the stain is not completely dry (up to 24 hours later), it remains sensitive to ambient conditions.<\/strong><\/p>\n<p>A common mistake is to only look at the daytime temperature. If the temperature drops too much in the evening, it can hinder drying. In some cases, the moisture contained in the stain can even react to the cold and compromise the finish.  <\/p>\n<div><\/div>\n<ul>\n<li>\n<h3>Avoid extreme temperatures<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p><strong>If you apply your stain when it&#8217;s too cold, it will not penetrate the wood well<\/strong>. This results in a more fragile finish, which risks peeling or wearing quickly.<strong>Conversely, in very hot weather, the stain dries too quickly on the surface<\/strong>. It doesn&#8217;t have time to penetrate correctly, and you also increase the risk of overlap marks.  <\/p>\n<p>In both cases, the problem is the same: <strong>a stain that doesn&#8217;t adhere properly&#8230; and reduced durability.<\/strong><\/p>\n<ul>\n<li>\n<h3>Avoid applying stain in direct sunlight<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>Applying in direct sunlight is not a good idea. <strong>Direct heat &#8220;cooks&#8221; the stain on the surface of the wood, which hinders its penetration<\/strong> and accelerates its drying time. This will result in more lap marks, as well as a less durable finish.<\/p>\n<div><\/div>\n<ul>\n<li>\n<h3>Monitor rain and humidity<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>Before you start, <strong>make sure you have at least 24 hours without rain ahead of you<\/strong>. A shower on fresh stain can dilute it, create marks, and weaken its resistance. <\/p>\n<p><strong>If dew falls immediately after application<\/strong>, it will negatively affect the result. Make sure there are <strong>at least a few hours between application and evening dew<\/strong>. <\/p>\n<div><\/div>\n<ul>\n<li>\n<h3>When is the best time to apply stain?<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>The best time to stain your patio is <strong>after the morning dew has evaporated, but before the intense heat of the afternoon<\/strong>.<\/p>\n<p>In practice, <strong>this is generally between 10 AM and 1:30 PM depending on the season and the positioning of your patio<\/strong>. This way, you avoid humidity, excessive heat, and overly intense sun. <\/p>\n<div><\/div>\n<ul>\n<li>\n<h3>Take the time to plan carefully<\/h3>\n<\/li>\n<\/ul>\n<div>\n<p>Before starting, <strong>always check the recommendations of your stain manufacturer<\/strong>. Each product has its specificities, particularly regarding drying time and humidity tolerance. By planning your project well and respecting the right conditions, you maximize your chances of obtaining a beautiful and long-lasting result.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Commence ton projet maintenant !<\/h3>\n<p>Tu trouveras tous les produits sur notre site web pour teindre ton patio comme un.e pro.<\/p>\n<ul>\n<li>Commence par mesurer les dimensions de ton patio pour savoir les quantit\u00e9s dont tu as besoin. \u00c0 titre d&#8217;exemple, pour un patio de 300 pi2 tu auras besoin de :\n<ul>\n<li>1 gallon de <a href=\"https:\/\/colobar.ca\/produits\/traitement-du-bois\/nettoyants\/sansin-multi-wash\/\">Multi-wash<\/a> ou 2 gallons de <a href=\"https:\/\/colobar.ca\/produits\/traitement-du-bois\/nettoyants\/sansin-wood-cleaner-nettoyeur-degrisonneur-pour-bois\/\">Wood Wash<\/a><\/li>\n<li>2 gallons de <a href=\"https:\/\/colobar.ca\/produits\/teinture-exterieure\/sansin-dec-teinture-pour-patios-en-bois\/\">Sansin Dec<\/a><\/li>\n<li>ou 5 L d&#8217;<a href=\"https:\/\/colobar.ca\/produits\/projets\/patio\/huile-alis-livos\/\">Huile pour terrasse Alis<\/a><\/li>\n<li>Entre 12 et 30 feuilles de <a href=\"https:\/\/colobar.ca\/produits\/section-pro\/sableur-de-plancher\/outils-application-et-papier-sable\/papier-sable-5po-8-trous-a-velcro-sableuse-orbitale\/\">papier sabl\u00e9 abrasif<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Choisis la finition qui convient le mieux \u00e0 tes go\u00fbts et \u00e0 ton patio:\n<ul>\n<li><a href=\"https:\/\/colobar.ca\/produits\/teinture-exterieure\/sansin-dec-teinture-pour-patios-en-bois\/\">Teinture semi-transparente<\/a><\/li>\n<li><a href=\"https:\/\/colobar.ca\/produits\/projets\/patio\/teinture-opaque-pour-terrasses-clotures-et-parements-enduradeck\/\">Teinture opaque<\/a><\/li>\n<li><a href=\"https:\/\/colobar.ca\/produits\/projets\/patio\/teinture-a-bois-transparente-ready-seal\/\">Huile p\u00e9n\u00e9trante<\/a><\/li>\n<\/ul>\n<\/li>\n<li>Passe ta commande et choisis entre le ramassage en magasin le jour m\u00eame ou la livraison \u00e0 domicile en 2 ou 3 jours ouvrables.<\/li>\n<\/ul>\n<p>Tu veux en apprendre plus sur la <a href=\"https:\/\/colobar.ca\/blog\/teinture-exterieure\/\">teinture ext\u00e9rieure<\/a> et le <a href=\"https:\/\/colobar.ca\/blog\/traitement-du-bois\/\">traitement du bois<\/a> ? On en parle dans notre blogue ![\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;7%&#8221; right_padding_desktop=&#8221;2%&#8221; top_padding_tablet=&#8221;10%&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#000000&#8243; text_direction=&#8221;ltr&#8221;]\n<h2>Q&amp;A<\/h2>\n[\/nectar_responsive_text][\/vc_column][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; left_padding_desktop=&#8221;15px&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;15px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#E4E0DB&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][toggles style=&#8221;animated_circle&#8221; animated_circle_position=&#8221;right&#8221; animated_circle_size=&#8221;40&#8243; animated_circle_bg_color=&#8221;#FFFFFF&#8221; animated_circle_gap=&#8221;10&#8243; accordion=&#8221;true&#8221; accordion_starting_functionality=&#8221;default&#8221; border_radius=&#8221;15px&#8221;][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 Why does my stain remain sticky?&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]This occurs mainly with penetrating oils. If the application conditions are not ideal (surface too humid, sun beating directly on the patio during application), the oil penetrates the wood poorly and remains on the surface, forming a sticky film. <\/p>\n<p>Respect the application conditions recommended by the manufacturer to prevent this from happening.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 I have darker areas than others after application. What happened? &#8220;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]This is generally caused by uneven wood absorption or inconsistent application. Some areas are more porous and absorb more stain, making them darker. To limit this phenomenon, it is necessary to work with uniform saturation and maintain a wet edge during application. If variations are already visible, a very light, uniformly applied coat can sometimes reduce contrasts.[\/vc_column_text][\/toggle][toggle color=&#8221;Accent-Color&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 What to do if dust or debris falls on fresh stain?&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]This is a common problem, especially outdoors. The reflex to intervene immediately can worsen the situation, as the surface is still wet. Wait until the stain is completely dry, then clean dry. Avoid using a cleaner during the first few days after application.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 Why does my stain wear out faster in certain areas?&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Areas with more traffic or exposure to more wear (under gutters, etc.) will wear down to bare wood more quickly.<\/p>\n<p>You can maintain these areas more regularly. If the rest of your patio still looks good, there&#8217;s no need to sand everything: only sand the most worn boards, then apply a first coat to the boards you sanded. Then, apply a second coat to the entire patio for a uniform look.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 Why doesn&#039;t my stain produce the expected color?&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]The final color depends heavily on the type of wood, its age, and its condition. Two different surfaces can react very differently to the same stain. To avoid surprises, it is always recommended to test on a small, inconspicuous area before staining the entire patio.[\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h4&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Q \u2013 How long should I wait before putting furniture back on the patio?&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Even if the surface seems dry after a few hours, the stain continues to harden deep down. Putting furniture back too soon can mark the finish or hinder its curing. It is therefore preferable to wait at least 24 to 48 hours, and avoid rugs for a few days to allow for proper curing.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;2%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-2-percent&#8221; column_padding_position=&#8221;left-right&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;3%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":16,"featured_media":149248,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[12253,12265,36,12254],"tags":[],"class_list":{"0":"post-149246","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-exterior-stain","8":"category-how-to","9":"category-uncategorized","10":"category-wood-patio"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Ultimate Guide to Staining a Wooden Deck<\/title>\n<meta name=\"description\" content=\"Colobar&#039;s experience and tips for staining a deck to achieve a durable and aesthetic finish. Sanding is key!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lire l&#039;article \ud83d\udc49\ufe0f The Ultimate Guide to Staining a Wooden Deck\" \/>\n<meta property=\"og:description\" content=\"Staining a patio is a project anyone can handle. However, achieving a beautiful result that lasts over time requires a bit more than simply applying a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/\" \/>\n<meta property=\"og:site_name\" content=\"Colobar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colobar\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-31T13:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T19:15:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fr\u00e9d\u00e9ric Riopel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fr\u00e9d\u00e9ric Riopel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"83 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/\"},\"author\":{\"name\":\"Fr\u00e9d\u00e9ric Riopel\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#\\\/schema\\\/person\\\/f4acf76e9691c3f74953a6ad08fb6473\"},\"headline\":\"The Ultimate Guide to Staining a Wooden Deck\",\"datePublished\":\"2022-05-31T13:00:48+00:00\",\"dateModified\":\"2026-05-05T19:15:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/\"},\"wordCount\":16559,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/guide-ultime-teinture-patio.jpg\",\"articleSection\":{\"0\":\"Exterior Stain\",\"1\":\"How-To\",\"3\":\"Wood Patio\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/\",\"url\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/\",\"name\":\"The Ultimate Guide to Staining a Wooden Deck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/guide-ultime-teinture-patio.jpg\",\"datePublished\":\"2022-05-31T13:00:48+00:00\",\"dateModified\":\"2026-05-05T19:15:08+00:00\",\"description\":\"Colobar's experience and tips for staining a deck to achieve a durable and aesthetic finish. Sanding is key!\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/guide-ultime-teinture-patio.jpg\",\"contentUrl\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/guide-ultime-teinture-patio.jpg\",\"width\":672,\"height\":375},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/colobar.ca\\\/en\\\/\",\"name\":\"Colobar\",\"description\":\"Painting and Decorating for Individuals and Businesses\",\"publisher\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colobar.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\",\"HomeAndConstructionBusiness\"],\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#organization\",\"name\":\"Colobar\",\"url\":\"https:\\\/\\\/colobar.ca\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colobar\\\/\",\"https:\\\/\\\/www.pinterest.ca\\\/colobar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/colobartv\"],\"description\":\"Magasin de peinture & d\u00e9coration sp\u00e9cialis\u00e9 dans la peinture, traitement du bois, rev\u00eatement \u00e9poxy, et la d\u00e9coration. Designer sur place.\",\"legalName\":\"Colobar Peinture & D\u00e9coration\",\"foundingDate\":\"1959-10-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/colobar.ca\\\/politiques-de-vente\\\/\"},\"address\":{\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"45.56725\",\"longitude\":\"-73.68827399999999\"},\"telephone\":[\"4506677200\",\"18446657200\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"telephone\":\"18446657200\",\"email\":\"info@colobar.ca\"},\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"09:00\",\"closes\":\"16:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"info@colobar.ca\",\"areaServed\":\"Grand Montr\u00e9al\",\"priceRange\":\"$$\",\"paymentAccepted\":\"Comptant, Visa, Mastercard, APPLE PAY\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/#\\\/schema\\\/person\\\/f4acf76e9691c3f74953a6ad08fb6473\",\"name\":\"Fr\u00e9d\u00e9ric Riopel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g\",\"caption\":\"Fr\u00e9d\u00e9ric Riopel\"},\"sameAs\":[\"frederic.riopel@colobar.ca\"],\"url\":\"https:\\\/\\\/colobar.ca\\\/en\\\/author\\\/frederic-riopel\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#local-main-place-address\",\"streetAddress\":\"357 boul. des Laurentides\",\"addressLocality\":\"Laval\",\"postalCode\":\"H7G 2T9\",\"addressRegion\":\"Qu\u00e9bec\",\"addressCountry\":\"CA\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/colobar.ca\\\/en\\\/the-ultimate-guide-to-staining-a-wooden-deck\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/cropped-logo-colobar-copy.png\",\"contentUrl\":\"https:\\\/\\\/colobar.ca\\\/wp-content\\\/uploads\\\/cropped-logo-colobar-copy.png\",\"width\":512,\"height\":512,\"caption\":\"Colobar\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Laval\" \/>\n<meta name=\"geo.position\" content=\"45.56725;-73.68827399999999\" \/>\n<meta name=\"geo.region\" content=\"Canada\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Ultimate Guide to Staining a Wooden Deck","description":"Colobar's experience and tips for staining a deck to achieve a durable and aesthetic finish. Sanding is key!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/","og_locale":"en_US","og_type":"article","og_title":"Lire l'article \ud83d\udc49\ufe0f The Ultimate Guide to Staining a Wooden Deck","og_description":"Staining a patio is a project anyone can handle. However, achieving a beautiful result that lasts over time requires a bit more than simply applying a","og_url":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/","og_site_name":"Colobar","article_publisher":"https:\/\/www.facebook.com\/colobar\/","article_published_time":"2022-05-31T13:00:48+00:00","article_modified_time":"2026-05-05T19:15:08+00:00","og_image":[{"width":672,"height":375,"url":"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg","type":"image\/jpeg"}],"author":"Fr\u00e9d\u00e9ric Riopel","twitter_misc":{"Written by":"Fr\u00e9d\u00e9ric Riopel","Est. reading time":"83 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#article","isPartOf":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/"},"author":{"name":"Fr\u00e9d\u00e9ric Riopel","@id":"https:\/\/colobar.ca\/en\/#\/schema\/person\/f4acf76e9691c3f74953a6ad08fb6473"},"headline":"The Ultimate Guide to Staining a Wooden Deck","datePublished":"2022-05-31T13:00:48+00:00","dateModified":"2026-05-05T19:15:08+00:00","mainEntityOfPage":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/"},"wordCount":16559,"commentCount":0,"publisher":{"@id":"https:\/\/colobar.ca\/en\/#organization"},"image":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#primaryimage"},"thumbnailUrl":"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg","articleSection":{"0":"Exterior Stain","1":"How-To","3":"Wood Patio"},"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/","url":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/","name":"The Ultimate Guide to Staining a Wooden Deck","isPartOf":{"@id":"https:\/\/colobar.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#primaryimage"},"image":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#primaryimage"},"thumbnailUrl":"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg","datePublished":"2022-05-31T13:00:48+00:00","dateModified":"2026-05-05T19:15:08+00:00","description":"Colobar's experience and tips for staining a deck to achieve a durable and aesthetic finish. Sanding is key!","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#primaryimage","url":"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg","contentUrl":"https:\/\/colobar.ca\/wp-content\/uploads\/guide-ultime-teinture-patio.jpg","width":672,"height":375},{"@type":"WebSite","@id":"https:\/\/colobar.ca\/en\/#website","url":"https:\/\/colobar.ca\/en\/","name":"Colobar","description":"Painting and Decorating for Individuals and Businesses","publisher":{"@id":"https:\/\/colobar.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colobar.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place","HomeAndConstructionBusiness"],"@id":"https:\/\/colobar.ca\/en\/#organization","name":"Colobar","url":"https:\/\/colobar.ca\/en\/","logo":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#local-main-organization-logo"},"image":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/colobar\/","https:\/\/www.pinterest.ca\/colobar\/","https:\/\/www.youtube.com\/colobartv"],"description":"Magasin de peinture & d\u00e9coration sp\u00e9cialis\u00e9 dans la peinture, traitement du bois, rev\u00eatement \u00e9poxy, et la d\u00e9coration. Designer sur place.","legalName":"Colobar Peinture & D\u00e9coration","foundingDate":"1959-10-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/colobar.ca\/politiques-de-vente\/"},"address":{"@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"45.56725","longitude":"-73.68827399999999"},"telephone":["4506677200","18446657200"],"contactPoint":{"@type":"ContactPoint","telephone":"18446657200","email":"info@colobar.ca"},"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday"],"opens":"09:00","closes":"16:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday","Sunday"],"opens":"00:00","closes":"00:00"}],"email":"info@colobar.ca","areaServed":"Grand Montr\u00e9al","priceRange":"$$","paymentAccepted":"Comptant, Visa, Mastercard, APPLE PAY"},{"@type":"Person","@id":"https:\/\/colobar.ca\/en\/#\/schema\/person\/f4acf76e9691c3f74953a6ad08fb6473","name":"Fr\u00e9d\u00e9ric Riopel","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0d24c405b72f2dc3099f8f67158db55b783c8bcdcdbc171d1e0a3182e7c6d5b?s=96&d=mm&r=g","caption":"Fr\u00e9d\u00e9ric Riopel"},"sameAs":["frederic.riopel@colobar.ca"],"url":"https:\/\/colobar.ca\/en\/author\/frederic-riopel\/"},{"@type":"PostalAddress","@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#local-main-place-address","streetAddress":"357 boul. des Laurentides","addressLocality":"Laval","postalCode":"H7G 2T9","addressRegion":"Qu\u00e9bec","addressCountry":"CA"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/colobar.ca\/en\/the-ultimate-guide-to-staining-a-wooden-deck\/#local-main-organization-logo","url":"https:\/\/colobar.ca\/wp-content\/uploads\/cropped-logo-colobar-copy.png","contentUrl":"https:\/\/colobar.ca\/wp-content\/uploads\/cropped-logo-colobar-copy.png","width":512,"height":512,"caption":"Colobar"}]},"geo.placename":"Laval","geo.position":{"lat":"45.56725","long":"-73.68827399999999"},"geo.region":"Canada"},"_links":{"self":[{"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/posts\/149246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/comments?post=149246"}],"version-history":[{"count":2,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/posts\/149246\/revisions"}],"predecessor-version":[{"id":154519,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/posts\/149246\/revisions\/154519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/media\/149248"}],"wp:attachment":[{"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/media?parent=149246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/categories?post=149246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colobar.ca\/en\/wp-json\/wp\/v2\/tags?post=149246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}